{"id":680,"date":"2022-07-08T15:29:24","date_gmt":"2022-07-08T13:29:24","guid":{"rendered":"https:\/\/www.studioplus-nantes.fr\/?p=680"},"modified":"2025-04-03T16:30:18","modified_gmt":"2025-04-03T14:30:18","slug":"big-fernand-tours","status":"publish","type":"post","link":"https:\/\/www.studioplus-nantes.fr\/index.php\/2022\/07\/08\/big-fernand-tours\/","title":{"rendered":"Big Fernand Tours"},"content":{"rendered":"\n<p><em>Type :<strong> <\/strong><\/em><strong>Restauration, ERP<\/strong><\/p>\n\n\n\n<p><em>Lieu : <\/em><strong>Tours (37)<\/strong><\/p>\n\n\n\n<p><em>Maitrise d\u2019ouvrage : <\/em><strong>Big Groupe, franchis\u00e9<\/strong><\/p>\n\n\n\n<p><em>Mission : <\/em><strong>Compl\u00e8te<\/strong><\/p>\n\n\n\n<p><em>Co\u00fbt des travaux :  <\/em><strong>300 000 \u20ac HT<\/strong><\/p>\n\n\n\n<p><em>Surface :&nbsp;<\/em><strong>140 m<sup>2<\/sup><\/strong><\/p>\n\n\n\n<p><em>Phase : &nbsp;<\/em><strong>Livr\u00e9 2020<\/strong><\/p>\n\n\n\n<p>Implant\u00e9 sur deux niveaux, en rez-de-chauss\u00e9e et au premier \u00e9tage, de deux immeubles mitoyens du centre-ville historique de Tours, ce restaurant de l\u2019enseigne de hamburgers artisanaux Big Fernand r\u00e9pond aux questions sp\u00e9cifiques li\u00e9es \u00e0 la r\u00e9habilitation de b\u00e2ti ancien, \u00e0 l\u2019inscription d\u2019un commerce dans un paysage urbain prot\u00e9g\u00e9, \u00e0 la cr\u00e9ation d\u2019un ERP et aux particularit\u00e9s propres au milieu de la restauration.<\/p>\n\n\n\n<p>Le concept esth\u00e9tique et technique propres \u00e0 l\u2019enseigne c\u00f4toient donc l\u2019identit\u00e9 du lieu. Le projet se dessine \u00e0 l\u2019\u00e9quilibre entre le respect de la charte Big Fernand et la conservation des sp\u00e9cificit\u00e9s du local, tout en r\u00e9pondant parfaitement \u00e0 toutes les exigences techniques et normatives d\u2019un projet de restauration.<\/p>\n\n\n\n<p>La pierre des murs, la chemin\u00e9e en briques et les poutres apparentes dialoguent donc avec le mobilier bois aux lignes sobres, le n\u00e9on int\u00e9rieur et les murs noirs dans une ambiance bistro contemporaine et d\u00e9cal\u00e9e.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"688\" src=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-768x1024.jpg\" alt=\"\" class=\"wp-image-688\" srcset=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-768x1024.jpg 768w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-225x300.jpg 225w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-1152x1536.jpg 1152w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-1536x2048.jpg 1536w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-600x800.jpg 600w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1482-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"685\" src=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-768x1024.jpg\" alt=\"\" class=\"wp-image-685\" srcset=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-768x1024.jpg 768w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-225x300.jpg 225w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-1152x1536.jpg 1152w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-1536x2048.jpg 1536w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-600x800.jpg 600w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1522-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"684\" src=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-768x1024.jpg\" alt=\"\" class=\"wp-image-684\" srcset=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-768x1024.jpg 768w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-225x300.jpg 225w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-1152x1536.jpg 1152w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-1536x2048.jpg 1536w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-600x800.jpg 600w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2020\/06\/IMG_1501-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"1723\" src=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-768x1024.jpg\" alt=\"\" class=\"wp-image-1723\" srcset=\"https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-768x1024.jpg 768w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-225x300.jpg 225w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-1152x1536.jpg 1152w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-1536x2048.jpg 1536w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-600x800.jpg 600w, https:\/\/www.studioplus-nantes.fr\/wp-content\/uploads\/2022\/07\/IMG_1523-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Type : Restauration, ERP Lieu : Tours (37) Maitrise d\u2019ouvrage : Big Groupe, franchis\u00e9 Mission : Compl\u00e8te Co\u00fbt des travaux : 300 000 \u20ac HT [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erp","category-restaurants"],"_links":{"self":[{"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/posts\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":22,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/posts\/680\/revisions"}],"predecessor-version":[{"id":1743,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/posts\/680\/revisions\/1743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/media\/751"}],"wp:attachment":[{"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/categories?post=680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studioplus-nantes.fr\/index.php\/wp-json\/wp\/v2\/tags?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}